{"id":1380,"date":"2013-04-26T21:22:49","date_gmt":"2013-04-26T19:22:49","guid":{"rendered":"http:\/\/www.radio-adapter.eu\/blog\/?p=1380"},"modified":"2016-05-27T06:51:35","modified_gmt":"2016-05-27T04:51:35","slug":"autoradio-tausch-vw-golf-plus-einbauanleitung","status":"publish","type":"post","link":"https:\/\/www.radio-adapter.eu\/blog\/2013\/04\/26\/autoradio-tausch-vw-golf-plus-einbauanleitung\/","title":{"rendered":"Autoradio Tausch VW Golf Plus Einbauanleitung"},"content":{"rendered":"<h1><b>VW Golf Plus: Radio tauschen!<\/b><\/h1>\n<p>Beim <strong><b>VW\u00a0Golf Plus ab<\/b><\/strong>\u00a02005 ist der Radiowechsel kein Problem. Man braucht nat\u00fcrlich einen entsprechenden Adapter sowie eine <a title=\"VW Radioblende\" href=\"http:\/\/www.car-hifi-radio-adapter.eu\/autoradioblende\/vw\/\" target=\"_blank\">VW Radioblende<\/a>, da die VW-Radios gr\u00f6\u00dfer sind, als die \u00fcblichen DIN-Gr\u00f6\u00dfen von Zubeh\u00f6rradios.<\/p>\n<p>Mit dem neuen Radio k\u00f6nnen alle modernen Quellen genutzt werden.<\/p>\n<ul>\n<li><b>Installationszeit: Zirka 45 Minuten eine Werkstatt wird nicht ben\u00f6tigt!<\/b><\/li>\n<li><b>Ausbauwerkzeug:\u00a0 Kunstoffhebel, Schraubenzieher!<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div>\n<dl id=\"attachment_290\">\n<dt><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plusradio1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1382\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plusradio1.jpg\" alt=\"Plusradio1\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plusradio1.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plusradio1-510x383.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plusradio1-150x113.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plusradio1-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/dt>\n<dd>VW\u00a0Golf Plus\u00a0Radio<\/dd>\n<\/dl>\n<\/div>\n<p><!--more--><\/p>\n<ul>\n<li><b>Schritt 1:\u00a0Die zwei kleinen F\u00e4cher oberhalb ausbauen mit Schraubenzieher aushebeln!<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1383\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus1.jpg\" alt=\"plus1\" width=\"600\" height=\"406\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus1.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus1-510x345.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus1-150x102.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus1-300x203.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<div>\n<dl id=\"attachment_293\">\n<dt><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1384\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus2.jpg\" alt=\"plus2\" width=\"600\" height=\"363\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus2.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus2-510x309.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus2-150x91.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus2-300x182.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/dt>\n<dd>\u00a0F\u00e4cher bei Golf Plus aushebeln<\/dd>\n<\/dl>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Es werden zwei Torxschrauben sichtbar, diese aufschrauben!<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plus3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1385\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plus3.jpg\" alt=\"Plus3\" width=\"600\" height=\"347\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plus3.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plus3-510x295.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plus3-150x87.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/Plus3-300x174.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong><strong>Mit dem Schraubenzieher vorsichtig die Abdeckung rundherum aufhebeln, die Abdeckung um das Radio ist geclipst!<\/strong><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div>\n<dl id=\"attachment_298\">\n<dt><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1386\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus4.jpg\" alt=\"plus4\" width=\"600\" height=\"327\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus4.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus4-510x278.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus4-150x82.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus4-300x164.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/dt>\n<dd><\/dd>\n<\/dl>\n<\/div>\n<ul>\n<li><b>Die Abdeckung nach vorne abheben!<\/b><\/li>\n<\/ul>\n<p><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1387\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus6.jpg\" alt=\"plus6\" width=\"600\" height=\"496\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus6.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus6-510x422.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus6-150x124.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus6-300x248.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/06\/Tiguanschablone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1647\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/06\/Tiguanschablone.jpg\" alt=\"Tiguanschablone\" width=\"600\" height=\"499\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/06\/Tiguanschablone.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/06\/Tiguanschablone-510x424.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/06\/Tiguanschablone-150x125.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/06\/Tiguanschablone-300x250.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<ul>\n<li><strong>Es werden vier Schrauben sichtbar diese l\u00f6sen und das Radio nach vorne rausziehen!<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Den original Radiostecker abziehen! Um das neue Radio einzubauen braucht man einen VW Radioadapter <\/b><\/li>\n<\/ul>\n<p><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1388\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus7.jpg\" alt=\"plus7\" width=\"600\" height=\"341\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus7.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus7-510x290.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus7-150x85.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus7-300x171.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<ul>\n<li><b>Der Antennenstecker ist ein Fakra Doppel-Stecker im VW\u00a0Golf Plus abziehen!\u00a0<\/b><\/li>\n<\/ul>\n<p><a href=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1389\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus8.jpg\" alt=\"plus8\" width=\"600\" height=\"355\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus8.jpg 600w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus8-510x302.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus8-150x89.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plus8-300x178.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Die meisten neuen Autoradios haben den DIN Antennenanschluss.<\/p>\n<p>Im VW Golf Plus kann ein 1 DIN oder Doppel DIN Autoradio verbaut werden wie das geht hast du in der Einbauanleitung erfahren und welche der <a href=\"http:\/\/www.radio-adapter.eu\/blog\/produkt-kategorie\/autoradio-blenden-sets\/vw-autoradio-blenden-sets\/vw-golf-plus-autoradio-blenden-sets\/\" target=\"_blank\">VW Golf Plus Autoradio Blenden Sets<\/a> das passende ist und zu diesen Fahrzeugtyp passt.<\/p>\n<p>Original ist ein Doppel DIN-Schacht Werksradio eingebaut die <a title=\"VW Radioblenden\" href=\"http:\/\/radio-adapter.eu\/home\/radioblenden\/vw\/\" target=\"_blank\">VW Radioblenden<\/a> erm\u00f6glicht die Reduktion auf ein 1 DIN Format oder auch Doppel DIN Format und man kann jedes handels\u00fcbliche Nachr\u00fcstradio verbauen.<\/p>\n<p>&nbsp;<\/p>\n<p>Das sollte ein vern\u00fcnftiges VW Golf Plus Radioeinbauset enthalten!<\/p>\n<ul>\n<li>Radioblende<\/li>\n<li>Radioadapter<\/li>\n<li>Antennenstecker <b>Fakra Doppel Anschluss!<\/b><\/li>\n<li>Entriegelungsb\u00fcgel<\/li>\n<\/ul>\n<p>Man kann die Adapter auch einzeln kaufen das zahlt sich aber meiste weniger aus als gleich ein ganzen Einbauset zu bestellen.<\/p>\n<p>&nbsp;<\/p>\n<p>Empfehlenswerte Anbieter wo man solche Sets bekommt gibt es einige zum Beispiel bei <a title=\"VW Golf Plus Radioblende\" href=\"http:\/\/www.radio-adapter.eu\/home\/radioblenden\/vw-golf-plus-autoradio-einbauset-radioeinbauset.html\" target=\"_blank\">VW Golf Plus Radioblende<\/a> radio-adapter.eu oder\u00a0<a title=\"Radioblende f\u00fcr VW Golf Plus\" href=\"http:\/\/www.autoradio-adapter.eu\/produkt\/vw-golf-plus-autoradio-einbauset-1-din-mit-fach\/\" target=\"_blank\">Radioblende f\u00fcr VW Golf Plus<\/a>\u00a0von autoradio-adapter.eu. Da kommt ales auf einmal und man braucht keine extra Teile um mit dem Einbau fertig zu werden.<\/p>\n<p>&nbsp;<\/p>\n<div>\n<dl id=\"attachment_303\">\n<dt><a title=\"VW Golf Plus Autoradio Einbauset f\u00fcr 1 DIN Radios mit Antennen Diversety\" href=\"http:\/\/www.car-hifi-radio-adapter.eu\/autoradioblende\/vw-golf-plus-autoradio-einbauset-radioeinbauset.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1589\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/61240setDiversety2.jpg\" alt=\"61240setDiversety2\" width=\"567\" height=\"482\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/61240setDiversety2.jpg 567w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/61240setDiversety2-510x434.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/61240setDiversety2-150x128.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/61240setDiversety2-300x255.jpg 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/dt>\n<dd>VW\u00a0Golf Plus\u00a0Autoradio Einbauset f\u00fcr 1 DIN Radios mit Antennen Diversety<\/dd>\n<\/dl>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div>\n<dl id=\"attachment_304\">\n<dt><a title=\"VW Golf Plus Autoradio Einbauset f\u00fcr Doppel DIN Radios\" href=\"http:\/\/www.car-hifi-radio-adapter.eu\/autoradioblende\/vw-golf-plus-doppel-din-autoradio-einbausatz.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1579\" src=\"http:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/05\/63114set21.jpg\" alt=\"63114set2\" width=\"567\" height=\"482\" srcset=\"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/05\/63114set21.jpg 567w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/05\/63114set21-510x434.jpg 510w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/05\/63114set21-150x128.jpg 150w, https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/05\/63114set21-300x255.jpg 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/dt>\n<dd>VW\u00a0Golf Plus\u00a0Autoradio Einbauset f\u00fcr Doppel DIN Radios<\/dd>\n<\/dl>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1>Wie Sie den Doppel DIN Blechrahmen des Einbausatzes einbauen und konfigurieren erfahren Sie hier unter <a title=\"Permanent Link to Doppel DIN Autoradio Blechrahmen Einbauanleitung\" href=\"http:\/\/www.radio-adapter.eu\/blog\/doppel-din-autoradio-blechrahmen-einbauanleitung\/\" rel=\"bookmark\">Doppel DIN Autoradio Blechrahmen Einbauanleitung<\/a><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VW Golf Plus: Radio tauschen! Beim VW\u00a0Golf Plus ab\u00a02005 ist der Radiowechsel kein Problem. Man braucht nat\u00fcrlich einen entsprechenden Adapter sowie eine VW Radioblende, da die VW-Radios gr\u00f6\u00dfer sind, als die \u00fcblichen DIN-Gr\u00f6\u00dfen von Zubeh\u00f6rradios. Mit dem neuen Radio k\u00f6nnen alle modernen Quellen genutzt werden. Installationszeit: Zirka 45 Minuten eine Werkstatt wird nicht ben\u00f6tigt! Ausbauwerkzeug:\u00a0 [&#8230;]\n","protected":false},"author":2,"featured_media":1390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,16],"tags":[85,1443,1456,2666,387,1444,1457,489,1445,1458,1446,1459,1447,1460,1448,1449,1450,1461,1462,1451,1463,3005,1314,1452,1453,1454,1464,1465,1466,1455,1467],"class_list":["post-1380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autoradio-einbauhilfe","category-vw-autoradio-einbauanleitungen","tag-anleitung-zum-radioausbau","tag-autoradio-ausbau-bei-vw-golf-plus","tag-autoradio-ausbau-bei-vw-golf-v-plus","tag-autoradio-einbau-golf-plus","tag-autoradio-tauschen-in-vw","tag-autoradio-tauschen-in-vw-golf-plus","tag-autoradio-tauschen-in-vw-golf-v-plus","tag-einbauanleitung-autoradio-wechsel","tag-neues-radio-fur-vw-golf-plus","tag-neues-radio-fur-vw-golf-v-plus","tag-original-vw-golf-plus-radio-ausbauen","tag-original-vw-golf-v-plus-radio-ausbauen","tag-radio-bei-vw-golf-plus-wechseln","tag-radio-bei-vw-golf-v-plus-wechseln","tag-radio-einbau-vw-golf","tag-radiowechsel-vw-golf-plus","tag-radiowechsel-vw-golf-plus-ab-2005","tag-radiowechsel-vw-golf-v-plus","tag-radiowechsel-vw-golf-v-plus-ab-2005","tag-ratgeber-autoradio-vw-golf-plus-tauschen","tag-ratgeber-autoradio-vw-golf-v-plus-tauschen","tag-vw-autoradio-einbauanleitungen","tag-vw-autoradio-tauschen","tag-vw-golf-plus-autoradio-einbauanleitung","tag-vw-golf-plus-autoradio-tauschen","tag-vw-golf-plus-radio-tauschen","tag-vw-golf-v-plus-autoradio-einbauanleitung","tag-vw-golf-v-plus-autoradio-tauschen","tag-vw-golf-v-plus-radio-tauschen","tag-wie-kann-ich-ein-autoradio-in-vw-golf-plus-einbauen","tag-wie-kann-ich-ein-autoradio-in-vw-golf-v-plus-einbauen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.radio-adapter.eu\/blog\/wp-content\/uploads\/2013\/04\/plusauto.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3srli-mg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/posts\/1380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":0,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/posts\/1380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/media?parent=1380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/categories?post=1380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/tags?post=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}