{"id":2926,"date":"2015-06-11T20:25:59","date_gmt":"2015-06-11T18:25:59","guid":{"rendered":"http:\/\/www.radio-adapter.eu\/blog\/agb\/"},"modified":"2015-06-16T08:56:47","modified_gmt":"2015-06-16T06:56:47","slug":"agb","status":"publish","type":"page","link":"https:\/\/www.radio-adapter.eu\/blog\/agb\/","title":{"rendered":"AGB"},"content":{"rendered":"<p><strong>Allgemeine Gesch\u00e4ftsbedingungen mit Kundeninformationen<\/strong><\/p>\n<p>(Die nachstehenden AGB enthalten zugleich gesetzliche Informationen zu Ihren Rechten nach den Vorschriften \u00fcber Vertr\u00e4ge im Fernabsatz und im elektronischen Gesch\u00e4ftsverkehr.)<\/p>\n<p>1. Geltungsbereich<br \/>\n2. Angebote und Leistungsbeschreibungen<br \/>\n3. Bestellvorgang und Vertragsabschluss<br \/>\n4. Preise und Versandkosten<br \/>\n5. Lieferung, Warenverf\u00fcgbarkeit<br \/>\n6. Zahlungsmodalit\u00e4ten<br \/>\n7. Eigentumsvorbehalt<br \/>\n8. Sachm\u00e4ngelgew\u00e4hrleistung und Garantie<br \/>\n9. Haftung<br \/>\n10. Speicherung des Vertragstextes<br \/>\n11. Datenschutz<br \/>\n12. Gerichtsstand, Anwendbares Recht, Vertragssprache<\/p>\n<p><em>1. Geltungsbereich<\/em><br \/>\n1.1. F\u00fcr die Gesch\u00e4ftsbeziehung zwischen \u201eVerk\u00e4ufer\u201c und dem Kunden gelten ausschlie\u00dflich die nachfolgenden Allgemeinen Gesch\u00e4ftsbedingungen in ihrer zum Zeitpunkt der Bestellung g\u00fcltigen Fassung.<\/p>\n<p>1.2. Sie erreichen unseren Kundendienst f\u00fcr Fragen, Reklamationen und Beanstandungen werktags von [9:00 UHR] bis [17:00 UHR] unter der Telefonnummer [<span class=\"label\"><span class=\"phone\">0043 463 292 141<\/span><\/span>] sowie per E-Mail unter office@radio-adapter.eu.<\/p>\n<p>1.3. Verbraucher im Sinne dieser AGB ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu einem Zwecke abschlie\u00dft, der \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbstst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden kann (\u00a7 13 BGB).<\/p>\n<p>1.4. Abweichende Bedingungen des Kunden werden nicht anerkannt, es sei denn, der Verk\u00e4ufer stimmt ihrer Geltung ausdr\u00fccklich zu.<\/p>\n<p><em>2. Angebote und Leistungsbeschreibungen<\/em><\/p>\n<p>2.1. Die Darstellung der Produkte im Online-Shop stellt kein rechtlich bindendes Angebot, sondern eine Aufforderung zur Abgabe einer Bestellung dar. Leistungsbeschreibungen in Katalogen sowie auf den Websites des Verk\u00e4ufers haben nicht den Charakter einer Zusicherung oder Garantie.<br \/>\n2.2. Alle Angebote gelten \u201esolange der Vorrat reicht\u201c, wenn nicht bei den Produkten etwas anderes vermerkt ist. Im \u00dcbrigen bleiben Irrt\u00fcmer vorbehalten.<\/p>\n<p><em>3. Bestellvorgang und Vertragsabschluss<\/em><\/p>\n<p>3.1. Der Kunde kann aus dem Sortiment des Verk\u00e4ufers Produkte unverbindlich ausw\u00e4hlen und diese \u00fcber die Schaltfl\u00e4che [in den Warenkorb] in einem so genannten Warenkorb sammeln. Anschlie\u00dfend kann der Kunde innerhalb des Warenkorbs \u00fcber die Schaltfl\u00e4che [Weiter zur Kasse] zum Abschluss des Bestellvorgangs schreiten.<\/p>\n<p>3.2. \u00dcber die Schaltfl\u00e4che [Kaufen] gibt der Kunde einen verbindlichen Antrag zum Kauf der im Warenkorb befindlichen Waren ab. Vor Abschicken der Bestellung kann der Kunde die Daten jederzeit \u00e4ndern und einsehen. Notwendige Angaben sind mit einem Sternchen (*) gekennzeichnet.<\/p>\n<p>3.3. Der Verk\u00e4ufer schickt daraufhin dem Kunden eine automatische Empfangsbest\u00e4tigung per E-Mail zu, in welcher die Bestellung des Kunden nochmals aufgef\u00fchrt wird und die der Kunde \u00fcber die Funktion \u201eDrucken\u201c ausdrucken kann (Bestellbest\u00e4tigung). Die automatische Empfangsbest\u00e4tigung dokumentiert lediglich, dass die Bestellung des Kunden beim Verk\u00e4ufer eingegangen ist und stellt keine Annahme des Antrags dar. Der Kaufvertrag kommt erst dann zustande, wenn der Verk\u00e4ufer das bestellte Produkt innerhalb von 2 Tagen an den Kunden versendet, \u00fcbergeben oder den Versand an den Kunden innerhalb von 2 Tagen mit einer zweiten E-Mail, ausdr\u00fccklicher Auftragsbest\u00e4tigung oder Zusendung der Rechnung best\u00e4tigt hat.<\/p>\n<p>3.4. Sollte der Verk\u00e4ufer eine Vorkassezahlung erm\u00f6glichen, kommt der Vertrag mit der Bereitstellung der Bankdaten und Zahlungsaufforderung zustande. Wenn die Zahlung trotz F\u00e4lligkeit auch nach erneuter Aufforderung nicht bis zu einem Zeitpunkt von 10 Kalendertagen nach Absendung der Bestellbest\u00e4tigung beim Verk\u00e4ufer eingegangen ist, tritt der Verk\u00e4ufer vom Vertrag zur\u00fcck mit der Folge, dass die Bestellung hinf\u00e4llig ist und den Verk\u00e4ufer keine Lieferpflicht trifft. Die Bestellung ist dann f\u00fcr den K\u00e4ufer und Verk\u00e4ufer ohne weitere Folgen erledigt. Eine Reservierung des Artikels bei Vorkassezahlungen erfolgt daher l\u00e4ngstens f\u00fcr 10 Kalendertage.<\/p>\n<p><em>4. Preise und Versandkosten<\/em><\/p>\n<p>4.1. Alle Preise, die auf der Website des Verk\u00e4ufers angegeben sind, verstehen sich einschlie\u00dflich der jeweils g\u00fcltigen gesetzlichen Umsatzsteuer.<\/p>\n<p>4.2. Zus\u00e4tzlich zu den angegebenen Preisen berechnet der Verk\u00e4ufer f\u00fcr die Lieferung Versandkosten. Die Versandkosten werden dem K\u00e4ufer auf einer gesonderten Informationsseite und im Rahmen des Bestellvorgangs deutlich mitgeteilt.<\/p>\n<p><em>5. Lieferung, Warenverf\u00fcgbarkeit<\/em><\/p>\n<p>5.1. Soweit Vorkasse vereinbart ist, erfolgt die Lieferung nach Eingang des Rechnungsbetrages.<\/p>\n<p>5.2. Sollten nicht alle bestellten Produkte vorr\u00e4tig sein, ist der Verk\u00e4ufer zu Teillieferungen auf seine Kosten berechtigt, soweit dies f\u00fcr den Kunden zumutbar ist.<\/p>\n<p>5.3. Sollte die Zustellung der Ware durch Verschulden des K\u00e4ufers trotz dreimaligem Auslieferversuchs scheitern, kann der Verk\u00e4ufer vom Vertrag zur\u00fccktreten. Ggf. geleistete Zahlungen werden dem Kunden unverz\u00fcglich erstattet.<\/p>\n<p>5.4. Wenn das bestellte Produkt nicht verf\u00fcgbar ist, weil der Verk\u00e4ufer mit diesem Produkt von seinem Lieferanten ohne eigenes Verschulden nicht beliefert wird, kann der Verk\u00e4ufer vom Vertrag zur\u00fccktreten. In diesem Fall wird der Verk\u00e4ufer den Kunden unverz\u00fcglich informieren und Ihnen ggf. die Lieferung eines vergleichbaren Produktes vorschlagen. Wenn kein vergleichbares Produkt verf\u00fcgbar ist oder der Kunde keine Lieferung eines vergleichbaren Produktes w\u00fcnscht, wird der Verk\u00e4ufer dem Kunden ggf. bereits erbrachte Gegenleistungen unverz\u00fcglich erstatten.<\/p>\n<p>5.5. Kunden werden \u00fcber Lieferzeiten und Lieferbeschr\u00e4nkungen (z.B. Beschr\u00e4nkung der Lieferungen auf bestimmten L\u00e4nder) auf einer gesonderten Informationsseite oder innerhalb der jeweiligen Produktbeschreibung unterrichtet.<\/p>\n<p><em>6. Zahlungsmodalit\u00e4ten<\/em><\/p>\n<p>6.1. Der Kunde kann im Rahmen und vor Abschluss des Bestellvorgangs aus den zur Verf\u00fcgung stehenden Zahlungsarten w\u00e4hlen. Kunden werden \u00fcber die zur Verf\u00fcgung stehenden Zahlungsmittel auf einer gesonderten Informationsseite unterrichtet.<\/p>\n<p>6.2. Ist die Bezahlung per Rechnung m\u00f6glich, hat die Zahlung innerhalb von 30 Tagen nach Erhalt der Ware und der Rechnung zu erfolgen. Bei allen anderen Zahlweisen hat die Zahlung im Voraus ohne Abzug zu erfolgen.<\/p>\n<p>6.3. Werden Drittanbieter mit der Zahlungsabwicklung beauftragt, z.B. Paypal. gelten deren Allgemeine Gesch\u00e4ftsbedingungen.<\/p>\n<p>6.4. Ist die F\u00e4lligkeit der Zahlung nach dem Kalender bestimmt, so kommt der Kunde bereits durch Vers\u00e4umung des Termins in Verzug. In diesem Fall hat der Kunde die gesetzlichen Verzugszinsen zu zahlen.<\/p>\n<p>6.5. Die Verpflichtung des Kunden zur Zahlung von Verzugszinsen schlie\u00dft die Geltendmachung weiterer Verzugssch\u00e4den durch den Verk\u00e4ufer nicht aus.<\/p>\n<p>6.6. Ein Recht zur Aufrechnung steht dem Kunden nur zu, wenn seine Gegenanspr\u00fcche rechtskr\u00e4ftig festgestellt oder von dem Verk\u00e4ufer anerkannt sind. Der Kunde kann ein Zur\u00fcckbehaltungsrecht nur aus\u00fcben, soweit die Anspr\u00fcche aus dem gleichen Vertragsverh\u00e4ltnis resultieren.<\/p>\n<p><em>7. Eigentumsvorbehalt<\/em><br \/>\nBis zur vollst\u00e4ndigen Bezahlung verbleiben die gelieferten Waren im Eigentum des Verk\u00e4ufers.<\/p>\n<p><em>8. Sachm\u00e4ngelgew\u00e4hrleistung und Garantie<\/em><\/p>\n<p>8.1. Die Gew\u00e4hrleistung bestimmt sich nach gesetzlichen Vorschriften.<\/p>\n<p>8.2. Eine Garantie besteht bei den vom Verk\u00e4ufer gelieferten Waren nur, wenn diese ausdr\u00fccklich abgegeben wurde. Kunden werden \u00fcber die Garantiebedingungen vor der Einleitung des Bestellvorgangs informiert.<\/p>\n<p><em>9. Haftung<\/em><\/p>\n<p>9.1. F\u00fcr eine Haftung des Verk\u00e4ufers auf Schadensersatz gelten unbeschadet der sonstigen gesetzlichen Anspruchsvoraussetzungen folgende Haftungsausschl\u00fcsse und -begrenzungen.<\/p>\n<p>9.2. Der Verk\u00e4ufer haftet unbeschr\u00e4nkt, soweit die Schadensursache auf Vorsatz oder grober Fahrl\u00e4ssigkeit beruht.<\/p>\n<p>9.3. Ferner haftet der Verk\u00e4ufer f\u00fcr die leicht fahrl\u00e4ssige Verletzung von wesentlichen Pflichten, deren Verletzung die Erreichung des Vertragszwecks gef\u00e4hrdet, oder f\u00fcr die Verletzung von Pflichten, deren Erf\u00fcllung die ordnungsgem\u00e4\u00dfe Durchf\u00fchrung des Vertrages \u00fcberhaupt erst erm\u00f6glicht und auf deren Einhaltung der Kunde regelm\u00e4\u00dfig vertraut. In diesem Fall haftet der Verk\u00e4ufer jedoch nur f\u00fcr den vorhersehbaren, vertragstypischen Schaden. Der Verk\u00e4ufer haftet nicht f\u00fcr die leicht fahrl\u00e4ssige Verletzung anderer als der in den vorstehenden S\u00e4tzen genannten Pflichten.<\/p>\n<p>9.4. Die vorstehenden Haftungsbeschr\u00e4nkungen gelten nicht bei Verletzung von Leben, K\u00f6rper und Gesundheit, f\u00fcr einen Mangel nach \u00dcbernahme einer Garantie f\u00fcr die Beschaffenheit des Produktes und bei arglistig verschwiegenen M\u00e4ngeln. Die Haftung nach dem Produkthaftungsgesetz bleibt unber\u00fchrt.<\/p>\n<p>9.5. Soweit die Haftung des Verk\u00e4ufers ausgeschlossen oder beschr\u00e4nkt ist, gilt dies auch f\u00fcr die pers\u00f6nliche Haftung von Arbeitnehmern, Vertretern und Erf\u00fcllungsgehilfen.<\/p>\n<p><em>10. Speicherung des Vertragstextes<\/em><\/p>\n<p>10.1. Der Kunde kann den Vertragstext vor der Abgabe der Bestellung an den Verk\u00e4ufer ausdrucken, indem er im letzten Schritt der Bestellung die Druckfunktion seines Browsers nutzt.<\/p>\n<p>10.2. Der Verk\u00e4ufer sendet dem Kunden au\u00dferdem eine Bestellbest\u00e4tigung mit allen Bestelldaten an die von Ihm angegebene E-Mail-Adresse zu. Mit der Bestellbest\u00e4tigung erh\u00e4lt der Kunde ferner eine Kopie der AGB nebst Widerrufsbelehrung und den Hinweisen zu Versandkosten sowie Liefer- und Zahlungsbedingungen. Sofern Sie sich in unserem Shop registriert haben sollten, k\u00f6nnen Sie in Ihrem Profilbereich Ihre aufgegebenen Bestellungen einsehen. Dar\u00fcber hinaus speichern wir den Vertragstext, machen ihn jedoch im Internet nicht zug\u00e4nglich.<\/p>\n<p><em>11. Datenschutz<\/em><\/p>\n<p>11.1. Der Verk\u00e4ufer verarbeitet personenbezogene Daten des Kunden zweckgebunden und gem\u00e4\u00df den gesetzlichen Bestimmungen.<\/p>\n<p>11.2. Die zum Zwecke der Bestellung von Waren angegebenen pers\u00f6nlichen Daten (wie zum Beispiel Name, E-Mail-Adresse, Anschrift, Zahlungsdaten) werden vom Verk\u00e4ufer zur Erf\u00fcllung und Abwicklung des Vertrags verwendet. Diese Daten werden vertraulich behandelt und nicht an Dritte weitergegeben, die nicht am Bestell-, Auslieferungs- und Zahlungsvorgang beteiligt sind.<\/p>\n<p>11.3. Der Kunde hat das Recht, auf Antrag unentgeltlich Auskunft zu erhalten \u00fcber die personenbezogenen Daten, die vom Verk\u00e4ufer \u00fcber ihn gespeichert wurden. Zus\u00e4tzlich hat er das Recht auf Berichtigung unrichtiger Daten, Sperrung und L\u00f6schung seiner personenbezogenen Daten, soweit keine gesetzliche Aufbewahrungspflicht entgegensteht.<\/p>\n<p>11.4. Weitere Informationen \u00fcber Art, Umfang, Ort und Zweck der Erhebung, Verarbeitung und Nutzung der erforderlichen personenbezogenen Daten durch den Verk\u00e4ufer finden sich in der Datenschutzerkl\u00e4rung.<\/p>\n<p><em>12. Gerichtsstand, Anwendbares Recht, Vertragssprache<\/em><\/p>\n<p>12.1. Gerichtstand und Erf\u00fcllungsort ist der Sitz des Verk\u00e4ufers, wenn der Kunde Kaufmann, juristische Person des \u00f6ffentlichen Rechts oder \u00f6ffentlich-rechtliches Sonderverm\u00f6gen ist.<\/p>\n<p>12.2. Vertragssprache ist deutsch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Allgemeine Gesch\u00e4ftsbedingungen mit Kundeninformationen (Die nachstehenden AGB enthalten zugleich gesetzliche Informationen zu Ihren Rechten nach den Vorschriften \u00fcber Vertr\u00e4ge im Fernabsatz und im elektronischen Gesch\u00e4ftsverkehr.) 1. Geltungsbereich 2. Angebote und Leistungsbeschreibungen 3. Bestellvorgang und Vertragsabschluss 4. Preise und Versandkosten 5. Lieferung, Warenverf\u00fcgbarkeit 6. Zahlungsmodalit\u00e4ten 7. Eigentumsvorbehalt 8. Sachm\u00e4ngelgew\u00e4hrleistung und Garantie 9. Haftung 10. Speicherung des [&#8230;]\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2926","page","type-page","status-publish","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/P3srli-Lc","jetpack_sharing_enabled":false,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/pages\/2926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/comments?post=2926"}],"version-history":[{"count":0,"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/pages\/2926\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.radio-adapter.eu\/blog\/wp-json\/wp\/v2\/media?parent=2926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}